{"id":1990,"date":"2017-06-01T11:41:04","date_gmt":"2017-06-01T10:41:04","guid":{"rendered":"https:\/\/vinsetvintage.fr\/?p=1990"},"modified":"2021-05-03T17:59:46","modified_gmt":"2021-05-03T16:59:46","slug":"auto-taille-xxl-margaux-jaguar-mk-x","status":"publish","type":"post","link":"https:\/\/vinsetvintage.fr\/index.php\/2017\/06\/01\/auto-taille-xxl-margaux-jaguar-mk-x\/","title":{"rendered":"Une auto taille XXL \u00e0 Margaux, la Jaguar MK X"},"content":{"rendered":"<p><span style=\"text-decoration: underline;\"><span style=\"color: #993366;\"><em>Chez les Lurton, le patriarche Lucien a l\u00e9gu\u00e9 ses dix ch\u00e2teaux \u00e0 ses dix enfants ! Son fils Denis a h\u00e9rit\u00e9 de Ch\u00e2teau Desmirail et de sa Jaguar, MK X la plus longue jamais fabriqu\u00e9e.<\/em><\/span><\/span><\/p>\n<p><!--more--><\/p>\n<p><strong>Ch\u00e2teau Desmirail<\/strong>, Denis Lurton<\/p>\n<p>\u201cIl y en a des chevaux sous le capot !\u201d Vous pensez sans doute que Denis Lurton vous parle de sa Jaguar MK X gar\u00e9e dans la cour de Ch\u00e2teau Desmiral, vu son 6 cylindres en ligne 3,8 l de 265 ch. Le m\u00eame que dans les fameuses Type E, mais qui propulsait ici cette \u00e9norme limousine \u00e0 la ligne tr\u00e8s aristocratique de 1,9 tonne \u00e0 pr\u00e8s de 200 km\/h en 1963. <img loading=\"lazy\" class=\"aligncenter size-full wp-image-1983\" src=\"https:\/\/vinsetvintage.fr\/wp-content\/uploads\/2017\/05\/P1030791-copie-3.jpg\" alt=\"Jaguar MKX de Denis Lurton \u00e0 chateau Desmirail\" width=\"1280\" height=\"960\" srcset=\"https:\/\/vinsetvintage.fr\/wp-content\/uploads\/2017\/05\/P1030791-copie-3.jpg 1280w, https:\/\/vinsetvintage.fr\/wp-content\/uploads\/2017\/05\/P1030791-copie-3-300x225.jpg 300w, https:\/\/vinsetvintage.fr\/wp-content\/uploads\/2017\/05\/P1030791-copie-3-768x576.jpg 768w, https:\/\/vinsetvintage.fr\/wp-content\/uploads\/2017\/05\/P1030791-copie-3-1024x768.jpg 1024w, https:\/\/vinsetvintage.fr\/wp-content\/uploads\/2017\/05\/P1030791-copie-3-1140x855.jpg 1140w\" sizes=\"(max-width: 1280px) 100vw, 1280px\" \/>Mais non. Passionn\u00e9 des deux, c\u2019est son puissant Grand Cru de Margaux 2008 qu\u2019il \u00e9voque ainsi, en vantant sa densit\u00e9 tannique amen\u00e9e par 3% de petit verdot, et la forte proportion de merlot (40%) pour lui donner une rondeur \u00e9l\u00e9gante et longue en bouche. \u201cComme une acc\u00e9l\u00e9ration grisante qui n\u2019en finit pas\u2026\u201d Ce go\u00fbt pour les m\u00e9taphores, Denis Lurton le tient sans doute de sa vie ant\u00e9rieure d\u2019avocat et d\u2019acteur de th\u00e9\u00e2tre. <img loading=\"lazy\" class=\"aligncenter size-full wp-image-1980\" src=\"https:\/\/vinsetvintage.fr\/wp-content\/uploads\/2017\/05\/P1030812-copie-2.jpg\" alt=\"Jaguar MKX de Denis Lurton \u00e0 chateau Desmirail\" width=\"1024\" height=\"663\" srcset=\"https:\/\/vinsetvintage.fr\/wp-content\/uploads\/2017\/05\/P1030812-copie-2.jpg 1024w, https:\/\/vinsetvintage.fr\/wp-content\/uploads\/2017\/05\/P1030812-copie-2-300x194.jpg 300w, https:\/\/vinsetvintage.fr\/wp-content\/uploads\/2017\/05\/P1030812-copie-2-768x497.jpg 768w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/>Mais en fait, un m\u00eame lien patrimonial explique cet attachement au Margaux et \u00e0 la Jaguar MK X. Car ce n\u2019est pas rien d\u2019\u00eatre un des fils de Lucien Lurton, l\u2019homme aux dix ch\u00e2teaux qui en l\u00e9gua un \u00e0 chacun de ses enfants en 1992 \u00e0 l\u2019age de 67 ans. En leur intimant de tous rentrer au bercail. \u201cPour moi, c\u2019\u00e9tait les 36 ha de Desmirail, et \u00e7a tombait plut\u00f4t bien, plaisante -t- il. Les initiales \u201cDL\u201d (Desmirail-Lurton) grav\u00e9es sur le fronton du domaine sont les m\u00eames que les miennes !\u00a0\u00bb <img loading=\"lazy\" class=\"aligncenter size-full wp-image-1988\" src=\"https:\/\/vinsetvintage.fr\/wp-content\/uploads\/2017\/05\/P1030796-copie-3.jpg\" alt=\"P1030796 - copie 3\" width=\"1280\" height=\"824\" srcset=\"https:\/\/vinsetvintage.fr\/wp-content\/uploads\/2017\/05\/P1030796-copie-3.jpg 1280w, https:\/\/vinsetvintage.fr\/wp-content\/uploads\/2017\/05\/P1030796-copie-3-300x193.jpg 300w, https:\/\/vinsetvintage.fr\/wp-content\/uploads\/2017\/05\/P1030796-copie-3-768x494.jpg 768w, https:\/\/vinsetvintage.fr\/wp-content\/uploads\/2017\/05\/P1030796-copie-3-1024x659.jpg 1024w, https:\/\/vinsetvintage.fr\/wp-content\/uploads\/2017\/05\/P1030796-copie-3-1140x734.jpg 1140w\" sizes=\"(max-width: 1280px) 100vw, 1280px\" \/>Quant \u00e0 la Jaguar MK X , Lucien Lurton n\u2019avait rien trouv\u00e9 de mieux pour transporter sa nombreuse famille que d\u2019acheter d\u2019occasion cette limousine de 1963 d\u00e9mesur\u00e9e avec 5,10 m de long et presque 2 m de large ! Et qui transportait 140 litres d&rsquo;essence dans deux r\u00e9servoirs s\u00e9par\u00e9s, s&rsquo;ouvrant de chaque cot\u00e9 de la lunette arri\u00e8re, pour satisfaire sa voracit\u00e9 ! Avec interrupteur au tableau de bord pour passer de l&rsquo;un \u00e0 l&rsquo;autre.<\/p>\n<h5 style=\"text-align: center;\"><span style=\"color: #993366;\">Cette Jaguar ultra longue \u00e9tait con\u00e7ue pour le march\u00e9 am\u00e9ricain<\/span><\/h5>\n<p>Cette Jaguar MK X la plus longue jamais fabriqu\u00e9e pour conqu\u00e9rir le march\u00e9 am\u00e9ricain, a \u00e9t\u00e9 commercialis\u00e9e \u00e0 24 282 exemplaires entre 1961 et 1970, dont 10 900 \u00e0 partir de 1964 en version 4,2 l. Le patron, William Lyons, l\u2019avait \u00e9quip\u00e9e des techniques dernier cri pour en faire une limousine de prestige : freins \u00e0 disque, direction \u00e0 assistance variable, boite automatique Borg Warner, et&nbsp; la premi\u00e8re de la marque avec suspension \u00e0 quatre roues ind\u00e9pendantes,. <img loading=\"lazy\" class=\"aligncenter size-full wp-image-1981\" src=\"https:\/\/vinsetvintage.fr\/wp-content\/uploads\/2017\/05\/P1030811-copie-2.jpg\" alt=\"Jaguar MKX de Denis Lurton \u00e0 chateau Desmirail\" width=\"1280\" height=\"960\" srcset=\"https:\/\/vinsetvintage.fr\/wp-content\/uploads\/2017\/05\/P1030811-copie-2.jpg 1280w, https:\/\/vinsetvintage.fr\/wp-content\/uploads\/2017\/05\/P1030811-copie-2-300x225.jpg 300w, https:\/\/vinsetvintage.fr\/wp-content\/uploads\/2017\/05\/P1030811-copie-2-768x576.jpg 768w, https:\/\/vinsetvintage.fr\/wp-content\/uploads\/2017\/05\/P1030811-copie-2-1024x768.jpg 1024w, https:\/\/vinsetvintage.fr\/wp-content\/uploads\/2017\/05\/P1030811-copie-2-1140x855.jpg 1140w\" sizes=\"(max-width: 1280px) 100vw, 1280px\" \/>Aussi silencieuse et confortable qu\u2019une Rolls, mais pour trois fois moins cher \u00e0 l\u2019\u00e9poque, la Jaguar MK X \u00e9tait richement dot\u00e9e de tout le luxe britannique \u00e0 bord : canap\u00e9 de salon moelleux et contreportes en cuir, ronce de noyer \u00e0 profusion sur la planche de bord, les porti\u00e8res, les tablettes avec miroir pour les passagers arri\u00e8res\u2026 \u201cMais en 1970, mon p\u00e8re a fait une bonne affaire en l\u2019achetant au prix d\u2019une 2 CV Citro\u00ebn neuve ! sourit Denis Lurton. <img loading=\"lazy\" class=\"aligncenter size-full wp-image-1986\" src=\"https:\/\/vinsetvintage.fr\/wp-content\/uploads\/2017\/05\/P1030775-copie.jpg\" alt=\"P1030775 - copie\" width=\"963\" height=\"616\" srcset=\"https:\/\/vinsetvintage.fr\/wp-content\/uploads\/2017\/05\/P1030775-copie.jpg 963w, https:\/\/vinsetvintage.fr\/wp-content\/uploads\/2017\/05\/P1030775-copie-300x192.jpg 300w, https:\/\/vinsetvintage.fr\/wp-content\/uploads\/2017\/05\/P1030775-copie-768x491.jpg 768w\" sizes=\"(max-width: 963px) 100vw, 963px\" \/>Cette Jaguar MK X a \u00e9t\u00e9 une voiture affective, dit-il car on a ensuite beaucoup bricol\u00e9 dessus pendant les vacances avec mes cousins. Et dans les ann\u00e9es 90 elle a \u00e9t\u00e9 la voiture de tous les mariage de la famille avant de finir d\u00e9laiss\u00e9e dans le fond d\u2019un garage.\u201dMais en 2016, histoire de poursuivre la tradition, Denis Lurton l\u2019a r\u00e9cup\u00e9r\u00e9e pour la restaurer et la faire revivre. A 56 ans, dernier de la fratrie \u00e0 y passer : il s\u2019est mari\u00e9 avec !<\/p>\n<p><img loading=\"lazy\" class=\"wp-image-1985 aligncenter\" src=\"https:\/\/vinsetvintage.fr\/wp-content\/uploads\/2017\/05\/P1030815-copie-3.jpg\" alt=\"P1030815 - copie 3\" width=\"302\" height=\"205\" srcset=\"https:\/\/vinsetvintage.fr\/wp-content\/uploads\/2017\/05\/P1030815-copie-3.jpg 1024w, https:\/\/vinsetvintage.fr\/wp-content\/uploads\/2017\/05\/P1030815-copie-3-300x204.jpg 300w, https:\/\/vinsetvintage.fr\/wp-content\/uploads\/2017\/05\/P1030815-copie-3-768x521.jpg 768w\" sizes=\"(max-width: 302px) 100vw, 302px\" \/><\/p>\n<p><a href=\"http:\/\/www.desmirail.com\">www.desmirail.com<\/a><\/p>\n<p>&nbsp;<\/p>\n<p><strong>LA M\u00caME MARQUE AUJOURD\u2019HUI<\/strong><\/p>\n<p><span style=\"text-decoration: underline;\"><em>Le Jaguar F-Pace 3.0 V6 S<\/em><\/span><\/p>\n<p><em><img loading=\"lazy\" class=\"alignleft wp-image-2007\" src=\"https:\/\/vinsetvintage.fr\/wp-content\/uploads\/2017\/05\/jaguarfpaceleslocation07.jpg\" alt=\"Jaguar F-Pace\" width=\"386\" height=\"195\"><\/em><\/p>\n<p>Histoire de ne pas laisser le champ libre \u00e0 ses concurrents Porsche, Audi ou BMW sur le cr\u00e9neau en plein boom des SUV, Jaguar a fini par sortir aussi le sien, le F-Pace. Plus puissant avec son V6 3l \u00e0 compresseur de 380 ch, le f\u00e9lin britannique part donc \u00e0 la chasse au Macan, son rival direct chez Porsche, avec un avantage \u2026<a href=\"https:\/\/vinsetvintage.fr\/?p=2011&amp;preview=true\">lire la suite<\/a><\/p>\n<p>&nbsp;<\/p>\n<p><strong>OENOTOURISME<\/strong><\/p>\n<p><em><u>&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp; Mon vin pr\u00e9f\u00e9r\u00e9<\/u><\/em><\/p>\n<p><img loading=\"lazy\" class=\"alignleft wp-image-2031\" src=\"https:\/\/vinsetvintage.fr\/wp-content\/uploads\/2017\/05\/ETIQ-DESMIRAIL-SANS-MILLESIME-V2-copie.jpg\" alt=\"Etiquette ch\u00e2teau Desmirail\" width=\"188\" height=\"277\" srcset=\"https:\/\/vinsetvintage.fr\/wp-content\/uploads\/2017\/05\/ETIQ-DESMIRAIL-SANS-MILLESIME-V2-copie.jpg 1004w, https:\/\/vinsetvintage.fr\/wp-content\/uploads\/2017\/05\/ETIQ-DESMIRAIL-SANS-MILLESIME-V2-copie-204x300.jpg 204w, https:\/\/vinsetvintage.fr\/wp-content\/uploads\/2017\/05\/ETIQ-DESMIRAIL-SANS-MILLESIME-V2-copie-768x1129.jpg 768w, https:\/\/vinsetvintage.fr\/wp-content\/uploads\/2017\/05\/ETIQ-DESMIRAIL-SANS-MILLESIME-V2-copie-697x1024.jpg 697w\" sizes=\"(max-width: 188px) 100vw, 188px\" \/><\/p>\n<p>Denis Lurton met un point d\u2019honneur \u00e0 ne vendre \u00e0 la&nbsp; propri\u00e9t\u00e9 que des vins difficilement trouvables dans le commerce de par leur vieillisemment effectu\u00e9 chez lui.<\/p>\n<p>&#8211;<strong>Desmirail 2008<\/strong>, ses 60% de cabernet sauvignon am\u00e8nent puissance et distinction \u00e0 ce Margaux Grand Cru de longue garde qui s\u2019arrondit avec une belle allonge soyeuse par ses 40% de merlot. Son nez ouvert en finesse l\u00e9g\u00e8rement vanill\u00e9 et min\u00e9ral lui donne toute son \u00e9l\u00e9gance. (38\u20ac)<\/p>\n<p>&#8211;<strong>Initial 2011<\/strong>, ce deuxi\u00e8me vin du domaine \u00e0 partir de vignes plus jeunes b\u00e9n\u00e9ficie du m\u00eame \u00e9levage en barriques. Il est explosif au nez avec une belle complexit\u00e9 aromatique et une touche de bois\u00e9. (20\u20ac)<\/p>\n<p>&nbsp;<\/p>\n<p><em><u>&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp; Profitez en pour visiter<\/u><\/em>\u2026<\/p>\n<p>* <strong>Blaye<\/strong> et sa citadelle construite par Vauban en surplomb de la Gironde pour bloquer l\u2019acc\u00e8s de Bordeaux \u00e0 la flotte anglaise avec, sur la rive oppos\u00e9e \u00e0 <strong>Cussac,<\/strong> Fort Medoc o\u00f9 l\u2019on rentre par la majestueuse porte Royale. La travers\u00e9e en bac sur 6 km entre Blaye et le port de Lamarque est d\u2019un d\u00e9paysement total.<\/p>\n<p>* <strong>Le Rigalet<\/strong>, charmant hameau aux petites maisons du XVIII \u00e8me au sud de Blaye.<\/p>\n<p>*<strong>La Tour Carnet<\/strong>, cette forteresse du XII \u00e8me \u00e0 St Laurent-du-M\u00e9doc abrite un des 4 grands crus de Bernard Magrez. A noter que le mus\u00e9e de ses voitures anciennes et de ses Rolls avec lesquelles il fait visiter ses ch\u00e2teaux dans un circuit oenotouristique a maintenant \u00e9lu domicile non loin de l\u00e0 dans son Cru bourgeois du Ch\u00e2teau Les Grands Ch\u00eanes \u00e0 Saint Christoly-M\u00e9doc .<\/p>\n<figure id=\"attachment_2036\" aria-describedby=\"caption-attachment-2036\" style=\"width: 1024px\" class=\"wp-caption alignleft\"><img loading=\"lazy\" class=\"size-full wp-image-2036\" src=\"https:\/\/vinsetvintage.fr\/wp-content\/uploads\/2017\/05\/BD-Tour-Carnet-1.jpg\" alt=\"Les Rolls de la Tour CArnet\" width=\"1024\" height=\"573\" srcset=\"https:\/\/vinsetvintage.fr\/wp-content\/uploads\/2017\/05\/BD-Tour-Carnet-1.jpg 1024w, https:\/\/vinsetvintage.fr\/wp-content\/uploads\/2017\/05\/BD-Tour-Carnet-1-300x168.jpg 300w, https:\/\/vinsetvintage.fr\/wp-content\/uploads\/2017\/05\/BD-Tour-Carnet-1-768x430.jpg 768w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><figcaption id=\"caption-attachment-2036\" class=\"wp-caption-text\">Le mus\u00e9e des Rolls \u00e0 la Tour Carnet.<\/figcaption><\/figure>\n<p>&nbsp;<\/p>\n<p>*<strong>Ch\u00e2teau Loudenne<\/strong>, ravissante chartreuse XVII \u00e8me \u00e0 <strong>St Yzans-de-M\u00e9doc<\/strong> avec jardins \u00e0 l\u2019anglaise descendant vers la Gironde, et mus\u00e9e dans les chais victoriens autour du travail de la vigne sur ce cru bourgeois.<\/p>\n<p>*<strong>Soulac<\/strong>, petite ville baln\u00e9aire aux charmantes maisons basses en briques et bois du XIX \u00e8me, et sa basilique romane dans laquelle on n\u2019entre pas, mais on descend ! Ce qui lui a valu d\u2019\u00eatre compl\u00e8tement ensabl\u00e9e avant d\u2019\u00eatre d\u00e9gag\u00e9e \u00e0 la fin du XIX \u00e8me. Un petit train touristique m\u00e8ne jusqu\u2019\u00e0 la Pointe de Grave.<\/p>\n<p>*<strong>Ch\u00e2teau Cos-d\u2019Estournel<\/strong>, en venant de Pauillac sur la D2, ne manquez pas, au d\u00e9tour d\u2019un virage en c\u00f4te, l\u2019apparition surr\u00e9aliste des pagodes indiennes du toit de cette b\u00e2tisse construite ainsi au XIX \u00e8me par son fondateur en souvenir de ses clients en Inde o\u00f9 il exportait ce grand cru aujourd\u2019hui propri\u00e9t\u00e9 de Michel Reybier. Cet ex cr\u00e9ateur de la marque Charcuteries d\u2019Aoste y a fait \u00e9difi\u00e9 un splendide chais par l\u2019architecte Jean-Michel Wilmotte.<\/p>\n<figure id=\"attachment_2037\" aria-describedby=\"caption-attachment-2037\" style=\"width: 1024px\" class=\"wp-caption alignleft\"><img loading=\"lazy\" class=\"size-full wp-image-2037\" src=\"https:\/\/vinsetvintage.fr\/wp-content\/uploads\/2017\/05\/BD-Cha\u0302teau-Cos-dEstournel-copie-1.jpg\" alt=\"Les curieuses tourelles en pagode du ch\u00e2teau Cos d'Estournel\" width=\"1024\" height=\"640\" srcset=\"https:\/\/vinsetvintage.fr\/wp-content\/uploads\/2017\/05\/BD-Cha\u0302teau-Cos-dEstournel-copie-1.jpg 1024w, https:\/\/vinsetvintage.fr\/wp-content\/uploads\/2017\/05\/BD-Cha\u0302teau-Cos-dEstournel-copie-1-300x188.jpg 300w, https:\/\/vinsetvintage.fr\/wp-content\/uploads\/2017\/05\/BD-Cha\u0302teau-Cos-dEstournel-copie-1-768x480.jpg 768w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><figcaption id=\"caption-attachment-2037\" class=\"wp-caption-text\">Les curieuses tourelles en pagode du ch\u00e2teau Cos-d&rsquo;Estournel.<\/figcaption><\/figure>\n<p>&nbsp;<\/p>\n<p>*<strong>Vertheuil<\/strong> , ancienne abbatiale du XI \u00e8me et son magnifique portail aux voussures orn\u00e9es de statues.<\/p>\n<p>*<strong>Port de Goul\u00e9e, Saint Christoly-Medoc<\/strong>, charmants ports o\u00f9 accostaient les bateaux pour charger les barriques de vins au debouch\u00e9 des canaux construits par les Hollandais au XVIII \u00e8me pour assainir les terrains avec des vannes bloquant les remont\u00e9es d\u2019eau de mer.<\/p>\n<p>*<strong>Ch\u00e2teau la tour de By<\/strong>, \u00e0 B\u00e9gadan, au milieu des vignes de ce grand cru, montez en haut de cette ancienne tour de guet qui offre un somptueux panorama sur l\u2019estuaire.<\/p>\n<p>*<strong>Bourg<\/strong>, on entre dans la ville basse par la rampe Cahoreau qui passe sous la porte de la Mer creus\u00e9e dans le rocher, pour grimper par les ruelles jusqu\u2019au ch\u00e2teau de la citadelle qui abr\u00eete un mus\u00e9e de cal\u00e8ches. Terrasse avec tr\u00e8s belle vue \u00e0 la fois sur la Dordogne, la Garonne et la Gironde. Un r\u00e9seau de salles souterraines surplombe l\u2019estuaire.<\/p>\n<figure id=\"attachment_2034\" aria-describedby=\"caption-attachment-2034\" style=\"width: 1024px\" class=\"wp-caption alignleft\"><img loading=\"lazy\" class=\"size-full wp-image-2034\" src=\"https:\/\/vinsetvintage.fr\/wp-content\/uploads\/2017\/05\/BD-TourdeBy1-jpg.jpg\" alt=\"En haut de l'ancienne tour de guet du domaine la tour de By, le panorama est super be sur la Gironde. \" width=\"1024\" height=\"683\" srcset=\"https:\/\/vinsetvintage.fr\/wp-content\/uploads\/2017\/05\/BD-TourdeBy1-jpg.jpg 1024w, https:\/\/vinsetvintage.fr\/wp-content\/uploads\/2017\/05\/BD-TourdeBy1-jpg-300x200.jpg 300w, https:\/\/vinsetvintage.fr\/wp-content\/uploads\/2017\/05\/BD-TourdeBy1-jpg-768x512.jpg 768w, https:\/\/vinsetvintage.fr\/wp-content\/uploads\/2017\/05\/BD-TourdeBy1-jpg-900x600.jpg 900w, https:\/\/vinsetvintage.fr\/wp-content\/uploads\/2017\/05\/BD-TourdeBy1-jpg-600x400.jpg 600w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><figcaption id=\"caption-attachment-2034\" class=\"wp-caption-text\">Du haut de l&rsquo;ancienne tour de guet du domaine La tour de By, la vue est superbe sur la Gironde.<\/figcaption><\/figure>\n<p>* <strong>Ch\u00e2teau du Bouilh<\/strong>, construit sur les plans de Victor Louis (architecte du Grand the\u00e2tre de Bordeaux). Il est rest\u00e9 inachev\u00e9 avec ses curieux communs en h\u00e9micycle.<\/p>\n<p>*<strong>Ch\u00e2teau Margaux<\/strong> , majestueux avec son escalier et ses colonnades, la plus belle fa\u00e7ade de ch\u00e2teau du M\u00e9doc construit en 1802 par l\u2019architecte Combes, \u00e9l\u00e8ve de Victor Louis. Visite des chais et de la cuverie de ce fameux Premier grand Cru.<\/p>\n<p>*<strong>Bayon-sur -Gironde<\/strong>, son \u00e9glise romane, son abside \u00e0 7 pans, et sur un impressionnant promontoire rocheux dominant la Gironde, les ch\u00e2teaux de Tayac et d\u2019Eyquem.<\/p>\n<p>*<strong>Phare de Cordouan<\/strong>, en vedette au d\u00e9part de la pointe de Grave \u00e0 Port-Bloc, la visite du plus beau phare de France avec ses \u00e9tages Renaissance, son portail monumental, l\u2019 appartement du Roi et la chapelle. www.phare-de-cordouan.fr<\/p>\n<figure id=\"attachment_1308\" aria-describedby=\"caption-attachment-1308\" style=\"width: 1280px\" class=\"wp-caption alignleft\"><img loading=\"lazy\" class=\"size-full wp-image-1308\" src=\"https:\/\/vinsetvintage.fr\/wp-content\/uploads\/2017\/01\/20150526_214428-copie.jpg\" alt=\"Les carrelets de p\u00eache sur pilotis sont nombreux le long de la Gironde.\" width=\"1280\" height=\"720\" srcset=\"https:\/\/vinsetvintage.fr\/wp-content\/uploads\/2017\/01\/20150526_214428-copie.jpg 1280w, https:\/\/vinsetvintage.fr\/wp-content\/uploads\/2017\/01\/20150526_214428-copie-300x169.jpg 300w, https:\/\/vinsetvintage.fr\/wp-content\/uploads\/2017\/01\/20150526_214428-copie-768x432.jpg 768w, https:\/\/vinsetvintage.fr\/wp-content\/uploads\/2017\/01\/20150526_214428-copie-1024x576.jpg 1024w, https:\/\/vinsetvintage.fr\/wp-content\/uploads\/2017\/01\/20150526_214428-copie-1140x641.jpg 1140w\" sizes=\"(max-width: 1280px) 100vw, 1280px\" \/><figcaption id=\"caption-attachment-1308\" class=\"wp-caption-text\">Les carrelets de p\u00eache sur pilotis sont nombreux le long de la Gironde.<\/figcaption><\/figure>\n<p>*<strong>Moulis-en-M\u00e9doc<\/strong>, son \u00e9glise romane aux fresques XII \u00e8me-XV \u00e8me et ses sarcophages m\u00e9rovingiens.<\/p>\n<p>*<strong>Saint Ciers-sur-Gironde<\/strong> et sa r\u00e9serve ornithologique de 120 ha avec tours d\u2019observation pour suivre les oiseaux sauvages et les migrateurs qui y font halte.<\/p>\n<p>* <strong>Promenades en kayak sur la Gironde<\/strong> depuis St Vivien de M\u00e9doc : Kayak et d\u00e9couvertes (06 88 77 53 29) ou M\u00e9doc Explorer Cano\u00eb (06 88 77 53 29)<\/p>\n<p>Consulter www.smiddest.fr<\/p>\n<p><span style=\"text-decoration: underline;\"><em>&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp; Publicit\u00e9<\/em><\/span><\/p>\n<p><em>&nbsp;<\/em><\/p>\n<h5>&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp; POUR UNE HALTE UN CHOIX S&rsquo;IMPOSE<\/h5>\n<p><img src=\"https:\/\/vinsetvintage.fr\/wp-content\/uploads\/2020\/06\/logo-41.jpg\"><\/p>\n<p><img loading=\"lazy\" class=\"aligncenter size-full wp-image-6677\" src=\"https:\/\/vinsetvintage.fr\/wp-content\/uploads\/2020\/06\/N\u00b0315-Suite-Prestige-Opera-View@Eric-Cuvillier-19-copie.jpg\" alt=\"\" width=\"1854\" height=\"1080\" srcset=\"https:\/\/vinsetvintage.fr\/wp-content\/uploads\/2020\/06\/N\u00b0315-Suite-Prestige-Opera-View@Eric-Cuvillier-19-copie.jpg 1854w, https:\/\/vinsetvintage.fr\/wp-content\/uploads\/2020\/06\/N\u00b0315-Suite-Prestige-Opera-View@Eric-Cuvillier-19-copie-300x175.jpg 300w, https:\/\/vinsetvintage.fr\/wp-content\/uploads\/2020\/06\/N\u00b0315-Suite-Prestige-Opera-View@Eric-Cuvillier-19-copie-768x447.jpg 768w, https:\/\/vinsetvintage.fr\/wp-content\/uploads\/2020\/06\/N\u00b0315-Suite-Prestige-Opera-View@Eric-Cuvillier-19-copie-1024x597.jpg 1024w, https:\/\/vinsetvintage.fr\/wp-content\/uploads\/2020\/06\/N\u00b0315-Suite-Prestige-Opera-View@Eric-Cuvillier-19-copie-1140x664.jpg 1140w\" sizes=\"(max-width: 1854px) 100vw, 1854px\" \/><\/p>\n<p><strong>&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp; LA R\u00c9F\u00c9RENCE DE L\u2019H\u00d4TELLERIE DE LUXE BORDELAISE<\/strong><\/p>\n<p>Situ\u00e9 sur la Place de la Com\u00e9die, en plein Triangle d\u2019or de la ville, et avec un parking en sous sol permettant de vous garer en toute s\u00e9curit\u00e9, l\u2019InterContinental Bordeaux &#8211; Le Grand H\u00f4tel est une l\u00e9gende de l\u2019h\u00f4tellerie depuis plus d\u2019un si\u00e8cle. Ancien h\u00f4tel particulier \u00e9rig\u00e9 en 1789 par Victor Louis, cet \u00e9difice class\u00e9 monument historique est devenu un h\u00f4tel pour la premi\u00e8re fois en 1904. Sa fa\u00e7ade n\u00e9o-classique aux colonnades de style corinthien fait face au majestueux Grand-Th\u00e9\u00e2tre de Bordeaux, achev\u00e9 dix ans plus t\u00f4t par le m\u00eame architecte. Au centre de ce quartier au riche pass\u00e9 mais en plein renouveau, l\u2019InterContinental Bordeaux &#8211; Le Grand H\u00f4tel est le point de d\u00e9part r\u00eav\u00e9 pour partir \u00e0 la d\u00e9couverte du Bordeaux d\u2019hier et d\u2019aujourd\u2019hui.<\/p>\n<p>L\u2019InterContinental Bordeaux &#8211; Le Grand H\u00f4tel poss\u00e8de 130 chambres, dont 44 suites. 21 d\u2019entre elles offrent une vue spectaculaire sur le Grand-Th\u00e9\u00e2tre (L\u2019Op\u00e9ra National de Bordeaux) et la place de la Com\u00e9die. Son d\u00e9cor \u00e9l\u00e9gant et feutr\u00e9, de style XVIII\u00e8me si\u00e8cle et Empire, a \u00e9t\u00e9 imagin\u00e9 par Jacques Garcia. Le c\u00e9l\u00e8bre d\u00e9corateur d\u2019int\u00e9rieur a sublim\u00e9 l\u2019esprit n\u00e9o-classique et cossu des lieux par son inimitable touche baroque.<\/p>\n<p>Aux r\u00eanes du restaurant gastronomique doublement \u00e9toil\u00e9&nbsp;: le chef britannique vedette Gordon Ramsay. Le restaurant Le Bordeaux, sur la place de la Com\u00e9die, propose une carte faite uniquement de produits locaux et de saison.<\/p>\n<p>Autre lieu embl\u00e9matique de l\u2019h\u00f4tel, le Rooftop&nbsp;: Cadre \u00e9l\u00e9gant et d\u00e9contract\u00e9 \u00e0 la fois, panorama unique \u00e0 360\u00b0 sur la cit\u00e9, atmosph\u00e8re conviviale mais exclusive&nbsp;: ce lounge \u00e0 ciel ouvert est \u00ab&nbsp;the place to be&nbsp;\u00bb<strong>.<\/strong><\/p>\n<p>Aux niveaux sup\u00e9rieurs de l\u2019\u00e9tablissement, un espace de d\u00e9tente et de relaxation unique : le Spa Guerlain<strong>. <\/strong>Ce lieu \u00e0 part fait plonger dans un univers tout en volupt\u00e9 \u00e9voquant les thermes romains, magnifi\u00e9 par la griffe de Jacques Garcia. Le bassin de relaxation est la pi\u00e8ce-ma\u00eetresse de ce spa dot\u00e9 de 8 cabines dont 2 doubles ainsi que d\u2019un sauna, hammam, d\u2019un espace fitness et d\u2019un salon de th\u00e9.<\/p>\n<p>Le Grand H\u00f4tel compte 13 salons d\u00e9di\u00e9s aux r\u00e9ceptions, r\u00e9unions et autres s\u00e9minaires, pouvant accueillir des \u00e9v\u00e9nements jusqu\u2019\u00e0 250 personnes. D\u2019une surface totale de 1.000 m\u00b2, ils b\u00e9n\u00e9ficient tous de la lumi\u00e8re naturelle du jour et sont associ\u00e9s \u00e0 4 majestueux foyers de 55 \u00e0 120 m\u00b2.<\/p>\n<p>L\u2019\u00e9quipe de quatre concierges, tous Clefs d\u2019Or, de l\u2019InterContinental Bordeaux &#8211; Le Grand H\u00f4tel ouvre les portes de la ville et de sa r\u00e9gion. Ils con\u00e7oivent des programmes sur mesure pour faire conna\u00eetre les tr\u00e9sors locaux &#8211; parmi lesquels, bien entendu, le plus c\u00e9l\u00e8bre vignoble du monde. Par le biais de leur Conciergerie, ils font p\u00e9n\u00e9trer leurs client\u00e8les dans l\u2019univers des grands crus traditionnellement ferm\u00e9 au grand public.<\/p>\n<p>T\u00e9moin et acteur privil\u00e9gi\u00e9 de la foisonnante histoire de Bordeaux et de son exceptionnel renouveau, l\u2019InterContinental Bordeaux &#8211; Le Grand H\u00f4tel est l\u2019endroit id\u00e9al pour vivre intimement la capitale girondine.<\/p>\n<p><strong>InterContinental Bordeaux &#8211; Le Grand Hotel<\/strong><\/p>\n<p>2-5 place de la Com\u00e9die, 33000 Bordeaux, France<br \/>\nHotel Phone: + 33 (0)5 57 30 44 44<\/p>\n<p><a href=\"http:\/\/www.bordeaux.intercontinental.com\/\">www.bordeaux.intercontinental.com<\/a><\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<h5><\/h5>\n<p><em>&nbsp; <\/em><\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Chez les Lurton, le patriarche Lucien a l\u00e9gu\u00e9 ses dix ch\u00e2teaux \u00e0 ses dix enfants ! Son fils Denis a h\u00e9rit\u00e9 de Ch\u00e2teau Desmirail et de sa Jaguar, MK X la plus longue jamais fabriqu\u00e9e.<\/p>\n","protected":false},"author":1,"featured_media":1982,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[4,527],"tags":[444],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v16.2 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Jaguar MK X Une auto XXL \u00e0 margaux \u00e0 Desmirail<\/title>\n<meta name=\"description\" content=\"Jaguar MK X de chateau Desmirail restaur\u00e9e par le vigneron Denis Lurton. Un paquebot de 5,10 m de long propuls\u00e9 par 6 cylindres 3,8 l\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/vinsetvintage.fr\/index.php\/2017\/06\/01\/auto-taille-xxl-margaux-jaguar-mk-x\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Jaguar MK X Une auto XXL \u00e0 margaux \u00e0 Desmirail\" \/>\n<meta property=\"og:description\" content=\"Jaguar MK X de chateau Desmirail restaur\u00e9e par le vigneron Denis Lurton. Un paquebot de 5,10 m de long propuls\u00e9 par 6 cylindres 3,8 l\" \/>\n<meta property=\"og:url\" content=\"https:\/\/vinsetvintage.fr\/index.php\/2017\/06\/01\/auto-taille-xxl-margaux-jaguar-mk-x\/\" \/>\n<meta property=\"og:site_name\" content=\"Vins &amp; Vintage\" \/>\n<meta property=\"article:published_time\" content=\"2017-06-01T10:41:04+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2021-05-03T16:59:46+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/vinsetvintage.fr\/wp-content\/uploads\/2017\/05\/GOOD1030784-copie-2.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1024\" \/>\n\t<meta property=\"og:image:height\" content=\"524\" \/>\n<meta name=\"twitter:card\" content=\"summary\" \/>\n<meta name=\"twitter:label1\" content=\"Dur\u00e9e de lecture est.\">\n\t<meta name=\"twitter:data1\" content=\"12 minutes\">\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebSite\",\"@id\":\"https:\/\/vinsetvintage.fr\/#website\",\"url\":\"https:\/\/vinsetvintage.fr\/\",\"name\":\"Vins &amp; Vintage\",\"description\":\"Le premier site des passionn\\u00e9s de voitures anciennes et de bons vins\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":\"https:\/\/vinsetvintage.fr\/?s={search_term_string}\",\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"ImageObject\",\"@id\":\"https:\/\/vinsetvintage.fr\/index.php\/2017\/06\/01\/auto-taille-xxl-margaux-jaguar-mk-x\/#primaryimage\",\"inLanguage\":\"fr-FR\",\"url\":\"https:\/\/vinsetvintage.fr\/wp-content\/uploads\/2017\/05\/GOOD1030784-copie-2.jpg\",\"contentUrl\":\"https:\/\/vinsetvintage.fr\/wp-content\/uploads\/2017\/05\/GOOD1030784-copie-2.jpg\",\"width\":1024,\"height\":524,\"caption\":\"Une auto XXL \\u00e0 Margaux, la Jaguar MK X\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/vinsetvintage.fr\/index.php\/2017\/06\/01\/auto-taille-xxl-margaux-jaguar-mk-x\/#webpage\",\"url\":\"https:\/\/vinsetvintage.fr\/index.php\/2017\/06\/01\/auto-taille-xxl-margaux-jaguar-mk-x\/\",\"name\":\"Jaguar MK X Une auto XXL \\u00e0 margaux \\u00e0 Desmirail\",\"isPartOf\":{\"@id\":\"https:\/\/vinsetvintage.fr\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/vinsetvintage.fr\/index.php\/2017\/06\/01\/auto-taille-xxl-margaux-jaguar-mk-x\/#primaryimage\"},\"datePublished\":\"2017-06-01T10:41:04+00:00\",\"dateModified\":\"2021-05-03T16:59:46+00:00\",\"author\":{\"@id\":\"https:\/\/vinsetvintage.fr\/#\/schema\/person\/ef3dad701eb0ac27543a0c1d0b993da9\"},\"description\":\"Jaguar MK X de chateau Desmirail restaur\\u00e9e par le vigneron Denis Lurton. Un paquebot de 5,10 m de long propuls\\u00e9 par 6 cylindres 3,8 l\",\"breadcrumb\":{\"@id\":\"https:\/\/vinsetvintage.fr\/index.php\/2017\/06\/01\/auto-taille-xxl-margaux-jaguar-mk-x\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/vinsetvintage.fr\/index.php\/2017\/06\/01\/auto-taille-xxl-margaux-jaguar-mk-x\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/vinsetvintage.fr\/index.php\/2017\/06\/01\/auto-taille-xxl-margaux-jaguar-mk-x\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"item\":{\"@type\":\"WebPage\",\"@id\":\"https:\/\/vinsetvintage.fr\/\",\"url\":\"https:\/\/vinsetvintage.fr\/\",\"name\":\"Accueil\"}},{\"@type\":\"ListItem\",\"position\":2,\"item\":{\"@id\":\"https:\/\/vinsetvintage.fr\/index.php\/2017\/06\/01\/auto-taille-xxl-margaux-jaguar-mk-x\/#webpage\"}}]},{\"@type\":\"Person\",\"@id\":\"https:\/\/vinsetvintage.fr\/#\/schema\/person\/ef3dad701eb0ac27543a0c1d0b993da9\",\"name\":\"Philippe Genet\",\"sameAs\":[\"http:\/\/vinsetvintage.fr\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","_links":{"self":[{"href":"https:\/\/vinsetvintage.fr\/index.php\/wp-json\/wp\/v2\/posts\/1990"}],"collection":[{"href":"https:\/\/vinsetvintage.fr\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/vinsetvintage.fr\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/vinsetvintage.fr\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/vinsetvintage.fr\/index.php\/wp-json\/wp\/v2\/comments?post=1990"}],"version-history":[{"count":41,"href":"https:\/\/vinsetvintage.fr\/index.php\/wp-json\/wp\/v2\/posts\/1990\/revisions"}],"predecessor-version":[{"id":8492,"href":"https:\/\/vinsetvintage.fr\/index.php\/wp-json\/wp\/v2\/posts\/1990\/revisions\/8492"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/vinsetvintage.fr\/index.php\/wp-json\/wp\/v2\/media\/1982"}],"wp:attachment":[{"href":"https:\/\/vinsetvintage.fr\/index.php\/wp-json\/wp\/v2\/media?parent=1990"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/vinsetvintage.fr\/index.php\/wp-json\/wp\/v2\/categories?post=1990"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/vinsetvintage.fr\/index.php\/wp-json\/wp\/v2\/tags?post=1990"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}